{"id":70856,"date":"2018-04-30T07:55:20","date_gmt":"2018-04-30T05:55:20","guid":{"rendered":"https:\/\/newsystem-detektiv-trails.ch\/shop\/detective-trail-soleure-vieille-ville-hiver\/"},"modified":"2026-06-29T17:22:02","modified_gmt":"2026-06-29T15:22:02","slug":"detective-trail-soleure-vieille-ville-hiver","status":"publish","type":"product","link":"https:\/\/detektiv-trails.ch\/fr\/produit\/detective-trail-soleure-vieille-ville-hiver\/","title":{"rendered":"D\u00e9tective-Trail: Soleure vieille ville hiver"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"70856\" class=\"elementor elementor-70856 elementor-69462\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8ab65f e-flex e-con-boxed e-con e-parent\" data-id=\"2b8ab65f\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1383c7 elementor-widget elementor-widget-text-editor\" data-id=\"6c1383c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>D\u00e9tective-Trail Soleure : toutes les infos et d\u00e9tails du jeu en un coup d&#8217;\u0153il<\/h2><p><strong>Heures d\u2019ouverture du Trail : <\/strong>Ouvert tous les jours <strong><span style=\"color: #79ced7\">du 1er novembre au 30 avril<\/span>\u00a0<\/strong>\u2013 \u00c0 tout moment<strong><br \/><\/strong>Du 1er mai au 31 octobre, le <strong><span style=\"color: #79ced7\"><a href=\"https:\/\/detektiv-trails.ch\/fr\/produit\/detective-trail-soleure-vieille-ville\/\" target=\"_blank\" rel=\"noopener\">Trail d&#8217;\u00e9t\u00e9 de Soleure <\/a><\/span><\/strong>est ouvert<strong><br \/><\/strong><strong>Variante du Trail : <\/strong>Avec coffre au tr\u00e9sor <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-52991\" src=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/05\/schatztruhe-300x300-1.jpg\" alt=\"\" width=\"26\" height=\"26\" \/><br \/>Le code de la version d\u2019hiver est diff\u00e9rent de celui de la version d\u2019\u00e9t\u00e9 ; la version d&#8217;hiver peut donc \u00eatre utilis\u00e9e du 1er novembre au 30 avril inclus.<br \/><strong>Acc\u00e8s au coffre au tr\u00e9sor :<br \/><\/strong>Du lundi au vendredi de 7h00 &#8211; 18h30, le samedi de 7h00 &#8211; 17h00, le dimanche de 9h00 &#8211; 17h00. Ferm\u00e9e le 25.12 et 01.01.<br \/>Informations sans garantie. Si le coffre au tr\u00e9sor n\u2019est pas accessible, nous t\u2019enverrons le cadeau ult\u00e9rieurement. Tu trouveras les informations concernant l\u2019exp\u00e9dition \u00e0 la fin du D\u00e9tective-Trail.<br \/><strong>Distance : <\/strong>env. 2.5 km<br \/><strong>Dur\u00e9e : <\/strong>env. 1 h 30 (sans pauses)<br \/><strong>D\u00e9part : <\/strong>Gare principale de Soleure (place de la gare)<br \/><strong>Lieu d\u2019arriv\u00e9e : <\/strong>Suteria, Hauptgasse 65, Soleure, <a href=\"https:\/\/www.suteria.ch\/de\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">www.suteria.ch<\/a><br \/><strong>Autres informations : <\/strong>Profite de l\u2019occasion pour prendre un ap\u00e9ritif ou un caf\u00e9 \u00e0 la Suteria (lieu d\u2019arriv\u00e9e). R\u00e9servation au 032 621 80 40.<br \/><strong>Poussettes : <\/strong>Le Trail est adapt\u00e9 aux poussettes.<strong> <a href=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-112000\" src=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen.jpg\" alt=\"\" width=\"26\" height=\"26\" srcset=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen.jpg 532w, https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen-300x300.jpg 300w, https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen-150x150.jpg 150w, https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/2023\/12\/detektiv-trails-Icon-Kinderwagen-100x100.jpg 100w\" sizes=\"auto, (max-width: 26px) 100vw, 26px\" \/><\/a><\/strong> Les escaliers entre les \u00e9nigmes 5 et 6 peuvent \u00eatre contourn\u00e9s.<br \/><strong>Point de vente sur place :<\/strong> Soleure Tourisme, Hauptgasse 69, 4500 Soleure. Contact et heures d\u2019ouverture de <a href=\"https:\/\/www.solothurn-city.ch\/fr\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Soleure Tourisme<\/a>.<br \/><strong>Degr\u00e9 de difficult\u00e9 : <\/strong>facile \u00e0 moyen<br \/><strong>Date de cr\u00e9ation : <\/strong>2016<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f7ca55 e-flex e-con-boxed e-con e-parent\" data-id=\"8f7ca55\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb78168 elementor-widget elementor-widget-heading\" data-id=\"cb78168\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Carte au tr\u00e9sor Soleure vielle ville hiver<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af82c8 elementor-widget elementor-widget-text-editor\" data-id=\"7af82c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"maps-marker-pro-345af901\" class=\"maps-marker-pro\" style=\"width: 100%;\">\r\n\t\t\t<div id=\"mmp-map-wrap-345af901\" class=\"mmp-map-wrap\">\r\n\t\t\t\t\t\t\t\t\t<div id=\"mmp-panel-345af901\" class=\"mmp-panel\"><\/div>\r\n\t\t\t\t\t\t\t\t<div id=\"mmp-map-345af901\" class=\"mmp-map\" style=\"height: 600px;\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec7031f elementor-widget elementor-widget-text-editor\" data-id=\"ec7031f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 data-path-to-node=\"3\">Chasse au tr\u00e9sor dans la ville du chiffre 11 : sur les traces de D\u00e9tective Blaireau durant la saison fra\u00eeche<\/h2><p data-path-to-node=\"5\">Bienvenue dans la plus belle ville baroque de Suisse ! Ce <b data-path-to-node=\"5\" data-index-in-node=\"58\">D\u00e9tective-Trail de Soleure<\/b> transforme les ruelles historiques en une v\u00e9ritable aventure en plein air. En deux mots, il s&#8217;agit d&#8217;une <strong>chasse au tr\u00e9sor<\/strong> captivante en compagnie de <strong>D\u00e9tective Blaireau.<\/strong><\/p><p data-path-to-node=\"5\">Votre aventure de fin limier commence directement sur la place de la gare (Bahnhofplatz), d&#8217;o\u00f9 l&#8217;itin\u00e9raire vous m\u00e8ne au c\u0153ur de la vieille ville \u2013 selon votre choix, avec la version imprim\u00e9e ou de mani\u00e8re tr\u00e8s flexible via l&#8217;application web sur votre smartphone. Au cours de ce <strong>jeu de piste vari\u00e9,<\/strong> vous percerez le secret du chiffre magique 11 \u00e0 <strong>l&#8217;imposante cath\u00e9drale Saint-Ours,<\/strong> admirerez la <strong>tour de l&#8217;horloge historique<\/strong> (Zeitglockenturm) ainsi que <strong>la c\u00e9l\u00e8bre horloge du 11<\/strong> (11i-Uhr) et ferez une halte passionnante au Mus\u00e9e de la nature. Toutes les \u00e9nigmes se r\u00e9solvent \u00e0 partir des \u00e9l\u00e9ments visibles sur place, ce qui vous permettra d&#8217;apprendre, l&#8217;air de rien, une foule d&#8217;anecdotes int\u00e9ressantes sur la magnifique ville au bord de l&#8217;Aar.<\/p><p data-path-to-node=\"6\">Comme ce parcours de 2,5 kilom\u00e8tres est volontairement con\u00e7u de mani\u00e8re compacte et qu&#8217;un escalier sur le chemin peut \u00eatre facilement contourn\u00e9, le trail est enti\u00e8rement accessible aux poussettes et constitue <strong>une id\u00e9e de sortie id\u00e9ale pour les familles,<\/strong> les \u00e9coles ou les associations. \u00c0 la fin, les solutions des diff\u00e9rents postes vous permettront <strong>de combiner votre code num\u00e9rique \u00e0 quatre chiffres.<\/strong> Au lieu d&#8217;arriv\u00e9e, la c\u00e9l\u00e8bre <strong>Suteria<\/strong> dans la rue principale (Hauptgasse), vous l&#8217;utiliserez pour crocheter le cadenas <strong>du coffre aux tr\u00e9sors<\/strong> et terminerez votre aventure en v\u00e9ritables ma\u00eetres d\u00e9tectives, avec une petite r\u00e9compense bien m\u00e9rit\u00e9e tir\u00e9e du coffre.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e0c8b6 e-flex e-con-boxed e-con e-parent\" data-id=\"5e0c8b6\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6ebf0e elementor-widget elementor-widget-heading\" data-id=\"e6ebf0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Autres offres de MyCityHighlight \u00e0 Soleure<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98e01b6 e-con-full e-flex e-con e-child\" data-id=\"98e01b6\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-eef78a8 e-con-full e-flex e-con e-child\" data-id=\"eef78a8\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e027eaf elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e027eaf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/elementor\/thumbs\/logo-krimi-trail-180-rk9d3zag3scljbkd9fwy8ng54bb8z0tjn82mnc2fvs.png\" title=\"logo-krimi-trail-180\" alt=\"logo-krimi-trail-180\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3629a87 e-con-full e-flex e-con e-child\" data-id=\"3629a87\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-341eccc elementor-widget elementor-widget-text-editor\" data-id=\"341eccc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Deviens enqu\u00eateur et r\u00e9sous des affaires criminelles sur le <a href=\"https:\/\/krimi-trails.ch\/fr\/produit\/crime-trail-soleure-vol-des-statues-en-or-du-tresor-du-dome-2\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Crime-Trail<\/a>.<br \/>Des exp\u00e9riences de loisirs pleines de suspense pour les fans de polar.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f21f7ce e-con-full e-flex e-con e-child\" data-id=\"f21f7ce\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-947e918 e-con-full e-flex e-con e-child\" data-id=\"947e918\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3e803b elementor-widget elementor-widget-image\" data-id=\"c3e803b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/detektiv-trails.ch\/wp-content\/uploads\/sites\/8\/elementor\/thumbs\/logo-finding-daniel-180-rk9cwpzbbuevvq3xnaynzhdzz737j605zapn8etvoy.png\" title=\"logo-finding-daniel-180\" alt=\"logo-finding-daniel-180\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f22b65 e-con-full e-flex e-con e-child\" data-id=\"7f22b65\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7abc7c8 elementor-widget elementor-widget-text-editor\" data-id=\"7abc7c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Partez pour une passionnante d\u00e9couverte de la ville.<br \/>Cherchez le guide Daniel lors du\u00a0<a href=\"https:\/\/www.finding-daniel.ch\/fr\/produit\/visiter-soleure-le-chiffre-sacre-11\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Finding-Daniel City Trail<\/a>\u00a0\u2013 la visite touristique avec effet jeu de piste.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans la plus belle ville baroque de Suisse !<\/p>\n<p>Accompagnez <strong>D\u00e9tective Blaireau<\/strong> pour <strong>une chasse au tr\u00e9sor captivante<\/strong> \u00e0 travers les ruelles historiques de Soleure. D\u00e9couvrez le chiffre magique 11, admirez la cath\u00e9drale Saint-Ours et r\u00e9solvez des \u00e9nigmes sur les fontaines et fa\u00e7ades. Chaque poste vous livre des <b data-path-to-node=\"17\" data-index-in-node=\"343\">informations passionnantes et surprenantes<\/b> sur l&#8217;histoire de la ville, transformant ce <strong>jeu de piste<\/strong> en une v\u00e9ritable visite p\u00e9dagogique. Si vous d\u00e9chiffrez les indices, le <strong>coffre au tr\u00e9sor<\/strong> et son <strong>prix imm\u00e9diat<\/strong> vous attendent !<\/p>\n<p>Une<strong> aventure <\/strong><b data-path-to-node=\"17\" data-index-in-node=\"591\">instructive et enrichissante<\/b> pour petits et grands au c\u0153ur de la cit\u00e9 des ambassadeurs.<\/p>\n","protected":false},"featured_media":143398,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[265,266,473,267,447,333,268],"product_tag":[409,410,475,411,412],"class_list":{"0":"post-70856","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-detective-trail-avec-coffre-au-tresor","7":"product_cat-detective-trail-avec-livraison-subsequente","8":"product_cat-detective-trails-a-soleure","9":"product_cat-les-cartes-de-detective-trails-en-suisse","10":"product_cat-espace-mittelland","11":"product_cat-freizeit-trails-fr","12":"product_cat-trails-francaises","13":"product_tag-detektiv-dachs-fr","14":"product_tag-detektiv-trail-fr","15":"product_tag-kinder-fr","16":"product_tag-schatzsuche-fr","17":"product_tag-schnitzeljagd-fr","18":"desktop-align-center","19":"tablet-align-left","20":"mobile-align-left","21":"ast-product-gallery-layout-horizontal-slider","22":"ast-magnify-disabled","23":"ast-product-tabs-layout-horizontal","25":"first","26":"outofstock","27":"featured","28":"virtual","29":"taxable","30":"purchasable","31":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product\/70856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/comments?post=70856"}],"version-history":[{"count":10,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product\/70856\/revisions"}],"predecessor-version":[{"id":172915,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product\/70856\/revisions\/172915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/media\/143398"}],"wp:attachment":[{"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/media?parent=70856"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=70856"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=70856"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/detektiv-trails.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=70856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}